{"id":48966,"date":"2026-02-28T08:58:00","date_gmt":"2026-02-28T07:58:00","guid":{"rendered":"https:\/\/www.zonderdank.be\/saturnein\/?p=48966"},"modified":"2026-02-28T07:36:09","modified_gmt":"2026-02-28T06:36:09","slug":"week-in-beeld-week-9-8","status":"publish","type":"post","link":"https:\/\/www.zonderdank.be\/saturnein\/2026\/02\/28\/week-in-beeld-week-9-8\/","title":{"rendered":"Week in beeld &#8211; week 9"},"content":{"rendered":"\n<p class=\"has-text-color has-link-color wp-elements-cfa74c847e804228a377761ae18e0819 wp-block-paragraph\" style=\"color:#783c77\"><em><strong>Vaste rubriek op zaterdag: week in beeld. Een greep uit de telefoonfoto\u2019s die ik maakte van zaterdagochtend tot vrijdagavond. Soms eens een foto door Meneertje Mertens. De laatste tijd ook vaker foto\u2019s met de Nikon. Maar vooral foto\u2019s van mijn telefoon.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vrijdag en zaterdag maak ik foto&#8217;s van de bloemetjes die ik voor mezelf kocht. Witte en roze tulpen. Eerst beneden, maar met het merendeel daarvan was ik niet echt happy (onscherp, damn winter). Gelukkig zaten er nog een paar goeie tussen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48963\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/dsc_7188-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7188-rotated.jpg?fit=810%2C1080&amp;ssl=1\" data-orig-size=\"810,1080\" data-comments-opened=\"1\" data-image-title=\"DSC_7188\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7188-rotated.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7188.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48963\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7188-rotated.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7188-rotated.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7188-rotated.jpg?w=810&amp;ssl=1 810w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zaterdag trek ik dus naar boven om opnieuw te beginnen. Heb me eigenlijk wel goed geamuseerd met &#8220;spelen met licht&#8221; (term waarvan ik de kriebels krijg wel). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48946\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260221_114507\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260221_114507.jpg?fit=1080%2C1440&amp;ssl=1\" data-orig-size=\"1080,1440\" data-comments-opened=\"1\" data-image-title=\"20260221_114507\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260221_114507.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260221_114507.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48946\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260221_114507.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260221_114507.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260221_114507.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Spelen met licht, maar ik hou wel van donkere foto&#8217;s. Maar ik heb nu dus ook nog 20 foto&#8217;s van witte en roze tulpen met en zonder druppels met allerlei verschillende lichtschakeringen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48964\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/dsc_7241\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7241-rotated.jpg?fit=810%2C1080&amp;ssl=1\" data-orig-size=\"810,1080\" data-comments-opened=\"1\" data-image-title=\"DSC_7241\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7241-rotated.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7241.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48964\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7241-rotated.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7241-rotated.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7241-rotated.jpg?w=810&amp;ssl=1 810w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maandag. We zijn hier dan weer h\u00e8. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48948\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_075615\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_075615.jpg?fit=1080%2C1440&amp;ssl=1\" data-orig-size=\"1080,1440\" data-comments-opened=\"1\" data-image-title=\"20260223_075615\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_075615.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_075615.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48948\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_075615.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_075615.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_075615.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eerst een foto voor Lili, met het beertje. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48947\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_074748\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_074748.jpg?fit=1080%2C1440&amp;ssl=1\" data-orig-size=\"1080,1440\" data-comments-opened=\"1\" data-image-title=\"20260223_074748\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_074748.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_074748.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48947\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_074748.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_074748.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_074748.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We hebben de hele dag onze bezigheid met het in de gaten houden van werkvolk. Deze kuist de ruiten met zijn spons (of wat het ook mag zijn) op een heel lange steel. (op \u00e9\u00e9n van de vorige foto&#8217;s zie je dat het wel nodig is dat de ruiten eens proper gemaakt worden). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"461\" height=\"1024\" data-attachment-id=\"48949\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_122747\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?fit=865%2C1920&amp;ssl=1\" data-orig-size=\"865,1920\" data-comments-opened=\"1\" data-image-title=\"20260223_122747\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?fit=461%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?resize=461%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48949\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?resize=461%2C1024&amp;ssl=1 461w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?resize=135%2C300&amp;ssl=1 135w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?resize=768%2C1705&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?resize=692%2C1536&amp;ssl=1 692w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_122747.jpg?w=865&amp;ssl=1 865w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Het is echt wel ambiance! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" data-attachment-id=\"48950\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_131209\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?fit=1920%2C865&amp;ssl=1\" data-orig-size=\"1920,865\" data-comments-opened=\"1\" data-image-title=\"20260223_131209\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?fit=1024%2C461&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?resize=1024%2C461&#038;ssl=1\" alt=\"\" class=\"wp-image-48950\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?resize=1536%2C692&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131209.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We zijn dan weer hier h\u00e8 (bis).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-attachment-id=\"48951\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_131237\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-title=\"20260223_131237\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?fit=1024%2C576&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-48951\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_131237.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De begeleidingsverpleegkundige komt langs, ziet mijn fototoestel liggen, en maakt eens een foto van ons beiden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"48965\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/dsc_7445-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?fit=1620%2C1080&amp;ssl=1\" data-orig-size=\"1620,1080\" data-comments-opened=\"1\" data-image-title=\"DSC_7445\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?fit=1024%2C683&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?resize=1024%2C683&#038;ssl=1\" alt=\"\" class=\"wp-image-48965\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/DSC_7445.jpg?w=1620&amp;ssl=1 1620w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ik laat Meneertje Mertens achter in het ziekenhuis, en ga te voet naar de Korenmarkt, waar ik een kwartier moet wachten op de bus. Ook ambiance. Beetje spijt dat ik eens geen filmpje gemaakt heb. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48952\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_172035\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172035.jpg?fit=1080%2C1440&amp;ssl=1\" data-orig-size=\"1080,1440\" data-comments-opened=\"1\" data-image-title=\"20260223_172035\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172035.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172035.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48952\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172035.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172035.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172035.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-attachment-id=\"48953\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_172244\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?fit=1080%2C1919&amp;ssl=1\" data-orig-size=\"1080,1919\" data-comments-opened=\"1\" data-image-title=\"20260223_172244\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?fit=576%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?resize=576%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48953\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?resize=576%2C1024&amp;ssl=1 576w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?resize=169%2C300&amp;ssl=1 169w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?resize=768%2C1365&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?resize=864%2C1536&amp;ssl=1 864w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_172244.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dinsdag breng ik de dag door bij <a href=\"https:\/\/www.defotoschuur.be\/\" target=\"_blank\" rel=\"noreferrer noopener\">de familie Fotoschuur<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48954\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260223_201741\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_201741.jpg?fit=1080%2C1440&amp;ssl=1\" data-orig-size=\"1080,1440\" data-comments-opened=\"1\" data-image-title=\"20260223_201741\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_201741.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_201741.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48954\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_201741.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_201741.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260223_201741.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Woensdag moeten ook zij naar het ziekenhuis (nog steeds niet hetzelfde als het onze). Zoek de baby. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48955\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260224_102224\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260224_102224.jpg?fit=1080%2C1440&amp;ssl=1\" data-orig-size=\"1080,1440\" data-comments-opened=\"1\" data-image-title=\"20260224_102224\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260224_102224.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260224_102224.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48955\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260224_102224.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260224_102224.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260224_102224.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ik trek weer naar de Korenmarkt. Het weer is fan-tas-tisch. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-attachment-id=\"48956\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260225_095819\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?fit=1080%2C1920&amp;ssl=1\" data-orig-size=\"1080,1920\" data-comments-opened=\"1\" data-image-title=\"20260225_095819\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?fit=576%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?resize=576%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48956\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?resize=576%2C1024&amp;ssl=1 576w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?resize=169%2C300&amp;ssl=1 169w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?resize=768%2C1365&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?resize=864%2C1536&amp;ssl=1 864w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095819.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nog een mottige foto, haha. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" data-attachment-id=\"48957\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260225_095948\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?fit=1920%2C865&amp;ssl=1\" data-orig-size=\"1920,865\" data-comments-opened=\"1\" data-image-title=\"20260225_095948\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?fit=1024%2C461&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?resize=1024%2C461&#038;ssl=1\" alt=\"\" class=\"wp-image-48957\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?resize=1536%2C692&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260225_095948.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hele dag zeggen ze in het ziekenhuis tegen ons dat het een mooie dag is om naar huis te gaan, maar de laatste ronde chemo start pas laat, en de ontslagpapieren laten op zich wachten tot na 3 uur. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Terug thuis. In de tuin bloeien de helleborussen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"48958\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260226_135105\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_135105.jpg?fit=1080%2C1440&amp;ssl=1\" data-orig-size=\"1080,1440\" data-comments-opened=\"1\" data-image-title=\"20260226_135105\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_135105.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_135105.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48958\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_135105.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_135105.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_135105.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donderdag is het lang wachten op de thuisverpleging voor een injectie voor Meneertje Mertens. Ik ga ondertussen toch maar een kort fietsritje maken in de buurt. De zon is zo enthousiast aanwezig, daar moet ik van genieten. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" data-attachment-id=\"48959\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260226_143025\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?fit=1920%2C865&amp;ssl=1\" data-orig-size=\"1920,865\" data-comments-opened=\"1\" data-image-title=\"20260226_143025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?fit=1024%2C461&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?resize=1024%2C461&#038;ssl=1\" alt=\"\" class=\"wp-image-48959\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?resize=1536%2C692&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143025.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Een stukje Lembeekse bossen (ook op de omslagfoto). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" data-attachment-id=\"48961\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260226_143240\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?fit=1920%2C865&amp;ssl=1\" data-orig-size=\"1920,865\" data-comments-opened=\"1\" data-image-title=\"20260226_143240\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?fit=1024%2C461&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?resize=1024%2C461&#038;ssl=1\" alt=\"\" class=\"wp-image-48961\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?resize=1536%2C692&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143240.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tussendoor is er breiwerk, het frustrerende truitje voor Suzi heb ik wat opzijgelegd, dit is een doodsimpel deken voor mezelf, het deken in mijn zetel is tot op de draad versleten en is aan vervanging toe. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"461\" height=\"1024\" data-attachment-id=\"48962\" data-permalink=\"https:\/\/www.zonderdank.be\/saturnein\/20260227_195713\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260227_195713-rotated.jpg?fit=486%2C1080&amp;ssl=1\" data-orig-size=\"486,1080\" data-comments-opened=\"1\" data-image-title=\"20260227_195713\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260227_195713-rotated.jpg?fit=461%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260227_195713.jpg?resize=461%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-48962\" srcset=\"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260227_195713-rotated.jpg?resize=461%2C1024&amp;ssl=1 461w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260227_195713-rotated.jpg?resize=135%2C300&amp;ssl=1 135w, https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260227_195713-rotated.jpg?w=486&amp;ssl=1 486w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoe was jouw week? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vaste rubriek op zaterdag: week in beeld. Een greep uit de telefoonfoto\u2019s die ik maakte van zaterdagochtend tot vrijdagavond. Soms eens een foto door Meneertje Mertens. De laatste tijd ook vaker foto\u2019s met de Nikon. Maar vooral foto\u2019s van mijn telefoon. Vrijdag en zaterdag maak ik foto&#8217;s van de bloemetjes die ik voor mezelf kocht. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48960,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1315],"tags":[2030,1233,1543,4575,4952,5889,3013,4170,1443],"class_list":["post-48966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotos","tag-az-sint-lucas","tag-breien-2","tag-gent","tag-helleborus","tag-sint-lucas","tag-suzilove","tag-tulp","tag-tulpen","tag-week-in-beeld"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.zonderdank.be\/saturnein\/wp-content\/uploads\/2026\/02\/20260226_143235.jpg?fit=1920%2C865&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2l47o-cJM","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/posts\/48966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/comments?post=48966"}],"version-history":[{"count":1,"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/posts\/48966\/revisions"}],"predecessor-version":[{"id":48967,"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/posts\/48966\/revisions\/48967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/media\/48960"}],"wp:attachment":[{"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/media?parent=48966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/categories?post=48966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zonderdank.be\/saturnein\/wp-json\/wp\/v2\/tags?post=48966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}